{"id":60488,"date":"2025-03-17T18:24:18","date_gmt":"2025-03-17T18:24:18","guid":{"rendered":"https:\/\/test.bluviva.fr\/product\/aquael-set-di-gamberi-smart-dn-20\/"},"modified":"2025-07-24T11:28:38","modified_gmt":"2025-07-24T11:28:38","slug":"aquael-set-di-gamberi-smart-dn-20","status":"publish","type":"product","link":"https:\/\/bluviva.com\/it\/prodotto\/aquael-set-di-gamberi-smart-dn-20\/","title":{"rendered":"AquaEL Set di gamberi Smart D&amp;N 20"},"content":{"rendered":"<h4><strong>SHRIMP Set GIORNO E NOTTE<\/strong><\/h4>\n<p><strong>BELLA SOTTO OGNI LUCE<\/strong><\/p>\n<p>Un set di acquari completo ed elegante che offre le condizioni ideali per la coltivazione di piante, gamberetti e piccoli pesci. Il moderno set comprende acquario, illuminazione, filtro interno e riscaldatore. <\/p>\n<p><strong>Design moderno<\/strong><\/p>\n<p>Shrimp Set Day&amp;Night \u00e8 un set funzionale caratterizzato da un design moderno e austero. L&#8217;acquario insieme al coperchio forma un cubo di vetro minimalista. Le dimensioni ridotte rendono l&#8217;acquario una decorazione originale anche per le stanze pi\u00f9 piccole.  <\/p>\n<p>Ci siamo anche presi cura della giusta dose di ispirazione. La confezione del set di gamberetti Day&amp;Night \u00e8 stata creata in collaborazione con il famoso acquascaping Michal Adamek e il team di Aquaman Studio. La confezione presenta foto di composizioni di esperti per incoraggiarti a creare le tue composizioni.  <\/p>\n<p><strong>Copertura funzionale<\/strong><\/p>\n<p>Il coperchio in vetro del Set non solo completa efficacemente l&#8217;insieme, ma ha anche applicazioni pratiche. Riduce l&#8217;evaporazione dell&#8217;acqua dall&#8217;acquario, tiene lontana la polvere dalla sua superficie e protegge dalle fughe incontrollate degli animali dalla vasca. <\/p>\n<p>La cura della vasca sar\u00e0 molto comoda. Il sistema Smart Open ti permette di tenere comodamente aperto il coperchio mentre ti occupi dell&#8217;interno dell&#8217;acquario. <\/p>\n<p><strong>Set completamente attrezzato<\/strong><\/p>\n<p>Ci siamo preoccupati di completare tutti i componenti necessari per avviare il tuo allevamento. Il set di gamberetti Day&amp;Night comprende: <\/p>\n<ul>\n<li>acquario a forma di cubo<\/li>\n<li>Leddy Illuminazione intelligente giorno e notte<\/li>\n<li>Filtro Turbo Mini<\/li>\n<li>Ripara il riscaldatore 2<\/li>\n<\/ul>\n<p>Puoi scegliere tra tre capacit\u00e0 di acquario: il pi\u00f9 piccolo ha 10 litri, il medio ne ha 19 e il pi\u00f9 grande di questo set ha 30 litri. Sono disponibili in due colori di finitura: bianco luminoso o nero classico. <\/p>\n<p><strong>Aggiunte complementari<\/strong><\/p>\n<p>Il Mini Filtro Turbo fornisce una filtrazione meccanica e biologica e un&#8217;aerazione dell&#8217;acqua. \u00c8 facile da usare: \u00e8 facile regolare l&#8217;uscita e la direzione del flusso d&#8217;acqua. <\/p>\n<p>Leddy Smart Day &amp; Night offre la possibilit\u00e0 di scegliere tra tre modalit\u00e0 di illuminazione che garantiscono un&#8217;illuminazione ottimale dell&#8217;acquario in diversi momenti della giornata. L&#8217;illuminazione diurna consiste in due modalit\u00e0: Day e Daybreak, che forniscono diverse intensit\u00e0 di luce. La modalit\u00e0 Notte \u00e8 una luce notturna che ti permetter\u00e0 di osservare la vita dell&#8217;acquario dopo il tramonto. Grazie ad essa, i pesci e le decorazioni fluorescenti brillano al buio e l&#8217;acquario assomiglia a una suggestiva luce notturna. Vale la pena notare anche il design minimalista della lampada, che si abbina perfettamente all&#8217;intero set. Inoltre, le lampade a LED (4,8 W) sono molto efficienti dal punto di vista energetico, il che si traduce in bollette pi\u00f9 basse.     <\/p>\n<p>Un riscaldatore Fix 2 completamente automatico si occuper\u00e0 di mantenere stabile la temperatura dell&#8217;acquario.<\/p>\n<p>Le decorazioni mostrate sulla confezione non sono incluse nel set.<\/p>\n<p><strong>Set completo<\/strong><\/p>\n<p>Shrimp Set Day&amp;Night offre le condizioni ideali per piante, gamberetti e piccoli pesci. Il benessere degli animali e la comodit\u00e0 d&#8217;uso sono assicurati: <\/p>\n<p>Leddy Smart Day &amp; Night 4,8W - 3 modalit\u00e0 di illuminazione: GIORNO \/ ALBA \/ NOTTE<\/p>\n<p>Filtro Turbo Mini 320 l\/h - regolazione dell&#8217;efficienza, dell&#8217;aerazione e della direzione del flusso d&#8217;acqua<\/p>\n<p>Sistema di riscaldamento intelligente Automatic Fix 2 - regola in modo indipendente la potenza di riscaldamento in base alle condizioni ambientali.<\/p>\n<p>Coperchio in vetro con sistema Smart Open<\/p>\n<p>Angoli minimalisti - protegge il fondo dell&#8217;acquario<\/p>\n<p>Il pacchetto comprende anche un design moderno e la certezza che l&#8217;intero set \u00e8 stato prodotto in Polonia, nel nostro stabilimento di Suwalki.<\/p>\n<\/p>\n<table style=\"width: 668px\">\n<tbody>\n<tr>\n<td style=\"width: 91px\">\n<p style=\"text-align: center\">\n<\/td>\n<td style=\"width: 83.5625px;text-align: center\">\n<p><strong>SHRIMP Set DAY&amp;NIGHT 10 Nero<\/strong><\/p>\n<\/td>\n<td style=\"width: 84.4375px;text-align: center\">\n<p><strong>SHRIMP Set DAY&amp;NIGHT 10 Bianco<\/strong><\/p>\n<\/td>\n<td style=\"width: 83px;text-align: center\">\n<p><strong>SHRIMP Set DAY&amp;NIGHT 20 Nero<\/strong><\/p>\n<\/td>\n<td style=\"width: 85px;text-align: center\">\n<p><strong>SHRIMP Set DAY&amp;NIGHT 20 Bianco<\/strong><\/p>\n<\/td>\n<td style=\"width: 85px;text-align: center\">\n<p><strong>SHRIMP Set DAY&amp;NIGHT 30 Nero<\/strong><\/p>\n<\/td>\n<td style=\"width: 86px;text-align: center\">\n<p><strong>SHRIMP Set DAY&amp;NIGHT 30 Bianco<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr style=\"text-align: center\">\n<td style=\"width: 91px\">\n<p><strong>Indice<\/strong><\/p>\n<\/td>\n<td style=\"width: 83.5625px\">\n<p>122976<\/p>\n<\/td>\n<td style=\"width: 84.4375px\">\n<p>122977<\/p>\n<\/td>\n<td style=\"width: 83px\">\n<p>122978<\/p>\n<\/td>\n<td style=\"width: 85px\">\n<p>122979<\/p>\n<\/td>\n<td style=\"width: 85px\">\n<p>122980<\/p>\n<\/td>\n<td style=\"width: 86px\">\n<p>122981<\/p>\n<\/td>\n<\/tr>\n<tr style=\"text-align: center\">\n<td style=\"width: 91px\">\n<p><strong>Capacit\u00e0 dell&#8217;acquario [L]<\/strong><\/p>\n<\/td>\n<td style=\"width: 83.5625px\">\n<p>10<\/p>\n<\/td>\n<td style=\"width: 84.4375px\">\n<p>10<\/p>\n<\/td>\n<td style=\"width: 83px\">\n<p>19<\/p>\n<\/td>\n<td style=\"width: 85px\">\n<p>19<\/p>\n<\/td>\n<td style=\"width: 85px\">\n<p>30<\/p>\n<\/td>\n<td style=\"width: 86px\">\n<p>30<\/p>\n<\/td>\n<\/tr>\n<tr style=\"text-align: center\">\n<td style=\"width: 91px\">\n<p><strong>Dimensioni [cm] (larghezza x profondit\u00e0 x altezza)<\/strong><\/p>\n<\/td>\n<td style=\"width: 83.5625px\">\n<p>20x20x25<\/p>\n<\/td>\n<td style=\"width: 84.4375px\">\n<p>20x20x25<\/p>\n<\/td>\n<td style=\"width: 83px\">\n<p>25X25X30<\/p>\n<\/td>\n<td style=\"width: 85px\">\n<p>25X25X30<\/p>\n<\/td>\n<td style=\"width: 85px\">\n<p>29X29X35<\/p>\n<\/td>\n<td style=\"width: 86px\">\n<p>29X29X35<\/p>\n<\/td>\n<\/tr>\n<tr style=\"text-align: center\">\n<td style=\"width: 91px\">\n<p><strong>Illuminazione<\/strong><\/p>\n<\/td>\n<td style=\"width: 83.5625px\">\n<p>Leddy Smart Day &amp; Night 4,8W<\/p>\n<\/td>\n<td style=\"width: 84.4375px\">\n<p>Leddy Smart Day &amp; Night 4,8W<\/p>\n<\/td>\n<td style=\"width: 83px\">\n<p>Leddy Smart Day &amp; Night 4,8W<\/p>\n<\/td>\n<td style=\"width: 85px\">\n<p>Leddy Smart Day &amp; Night 4,8W<\/p>\n<\/td>\n<td style=\"width: 85px\">\n<p>Leddy Smart Day &amp; Night 4,8W<\/p>\n<\/td>\n<td style=\"width: 86px\">\n<p>Leddy Smart Day &amp; Night 4,8W<\/p>\n<\/td>\n<\/tr>\n<tr style=\"text-align: center\">\n<td style=\"width: 91px\">\n<p><strong>Filtro<\/strong><\/p>\n<\/td>\n<td style=\"width: 83.5625px\">\n<p>Turbo Mini<\/p>\n<\/td>\n<td style=\"width: 84.4375px\">\n<p>Turbo Mini<\/p>\n<\/td>\n<td style=\"width: 83px\">\n<p>Turbo Mini<\/p>\n<\/td>\n<td style=\"width: 85px\">\n<p>Turbo Mini<\/p>\n<\/td>\n<td style=\"width: 85px\">\n<p>Turbo Mini<\/p>\n<\/td>\n<td style=\"width: 86px\">\n<p>Turbo Mini<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px;text-align: center\">\n<p><strong>Riscaldatore<\/strong><\/p>\n<\/td>\n<td style=\"width: 83.5625px;text-align: center\">\n<p>50W<\/p>\n<\/td>\n<td style=\"width: 84.4375px;text-align: center\">\n<p>50W<\/p>\n<\/td>\n<td style=\"width: 83px;text-align: center\">\n<p>50W<\/p>\n<\/td>\n<td style=\"width: 85px;text-align: center\">\n<p>50W<\/p>\n<\/td>\n<td style=\"width: 85px;text-align: center\">\n<p>50W<\/p>\n<\/td>\n<td style=\"width: 86px\">\n<p style=\"text-align: center\">50W<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>SHRIMP Set GIORNO E NOTTE BELLA SOTTO OGNI LUCE Un set di acquari completo ed elegante che offre le condizioni ideali per la coltivazione di piante, gamberetti e piccoli pesci. Il moderno set comprende acquario, illuminazione, filtro interno e riscaldatore. Design moderno Shrimp Set Day&amp;Night \u00e8 un set funzionale caratterizzato da un design moderno e [&hellip;]<\/p>\n","protected":false},"featured_media":27219,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[2749],"product_cat":[2472],"product_tag":[],"class_list":["post-60488","product","type-product","status-publish","has-post-thumbnail","product_brand-aquael-it","product_cat-piccolo-0-40l","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AquaEL Set di gamberi Smart D&amp;N 20 - Bluviva<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bluviva.com\/it\/prodotto\/aquael-set-di-gamberi-smart-dn-20\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AquaEL Set di gamberi Smart D&amp;N 20 - Bluviva\" \/>\n<meta property=\"og:description\" content=\"SHRIMP Set GIORNO E NOTTE BELLA SOTTO OGNI LUCE Un set di acquari completo ed elegante che offre le condizioni ideali per la coltivazione di piante, gamberetti e piccoli pesci. Il moderno set comprende acquario, illuminazione, filtro interno e riscaldatore. Design moderno Shrimp Set Day&amp;Night \u00e8 un set funzionale caratterizzato da un design moderno e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bluviva.com\/it\/prodotto\/aquael-set-di-gamberi-smart-dn-20\/\" \/>\n<meta property=\"og:site_name\" content=\"Bluviva\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61572180581409\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-24T11:28:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bluviva.com\/wp-content\/uploads\/2025\/03\/124835-SHRIMP-SET-SMART-DN-20-CZARNY-ECOM_8.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2042\" \/>\n\t<meta property=\"og:image:height\" content=\"2042\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bluviva.com\\\/it\\\/prodotto\\\/aquael-set-di-gamberi-smart-dn-20\\\/\",\"url\":\"https:\\\/\\\/bluviva.com\\\/it\\\/prodotto\\\/aquael-set-di-gamberi-smart-dn-20\\\/\",\"name\":\"AquaEL Set di gamberi Smart D&amp;N 20 - Bluviva\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bluviva.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bluviva.com\\\/it\\\/prodotto\\\/aquael-set-di-gamberi-smart-dn-20\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bluviva.com\\\/it\\\/prodotto\\\/aquael-set-di-gamberi-smart-dn-20\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bluviva.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/124835-SHRIMP-SET-SMART-DN-20-CZARNY-ECOM_8.webp\",\"datePublished\":\"2025-03-17T18:24:18+00:00\",\"dateModified\":\"2025-07-24T11:28:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bluviva.com\\\/it\\\/prodotto\\\/aquael-set-di-gamberi-smart-dn-20\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bluviva.com\\\/it\\\/prodotto\\\/aquael-set-di-gamberi-smart-dn-20\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/bluviva.com\\\/it\\\/prodotto\\\/aquael-set-di-gamberi-smart-dn-20\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bluviva.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/124835-SHRIMP-SET-SMART-DN-20-CZARNY-ECOM_8.webp\",\"contentUrl\":\"https:\\\/\\\/bluviva.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/124835-SHRIMP-SET-SMART-DN-20-CZARNY-ECOM_8.webp\",\"width\":2042,\"height\":2042},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bluviva.com\\\/it\\\/prodotto\\\/aquael-set-di-gamberi-smart-dn-20\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Casa\",\"item\":\"https:\\\/\\\/bluviva.com\\\/it\\\/casa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negozio\",\"item\":\"https:\\\/\\\/bluviva.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"AquaEL Set di gamberi Smart D&amp;N 20\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bluviva.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/bluviva.com\\\/it\\\/\",\"name\":\"Bluviva\",\"description\":\"Online Aquarium Shop\",\"publisher\":{\"@id\":\"https:\\\/\\\/bluviva.com\\\/it\\\/#organization\"},\"alternateName\":\"Bluviva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bluviva.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bluviva.com\\\/it\\\/#organization\",\"name\":\"Bluviva\",\"url\":\"https:\\\/\\\/bluviva.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/bluviva.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bluviva.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/474620657_122101559012739352_4098091748390755316_n.webp\",\"contentUrl\":\"https:\\\/\\\/bluviva.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/474620657_122101559012739352_4098091748390755316_n.webp\",\"width\":200,\"height\":200,\"caption\":\"Bluviva\"},\"image\":{\"@id\":\"https:\\\/\\\/bluviva.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61572180581409\",\"https:\\\/\\\/www.youtube.com\\\/@Bluviva\",\"https:\\\/\\\/www.instagram.com\\\/bluvivaeu\\\/\",\"https:\\\/\\\/pinterest.com\\\/bluviva\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AquaEL Set di gamberi Smart D&amp;N 20 - Bluviva","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bluviva.com\/it\/prodotto\/aquael-set-di-gamberi-smart-dn-20\/","og_locale":"it_IT","og_type":"article","og_title":"AquaEL Set di gamberi Smart D&amp;N 20 - Bluviva","og_description":"SHRIMP Set GIORNO E NOTTE BELLA SOTTO OGNI LUCE Un set di acquari completo ed elegante che offre le condizioni ideali per la coltivazione di piante, gamberetti e piccoli pesci. Il moderno set comprende acquario, illuminazione, filtro interno e riscaldatore. Design moderno Shrimp Set Day&amp;Night \u00e8 un set funzionale caratterizzato da un design moderno e [&hellip;]","og_url":"https:\/\/bluviva.com\/it\/prodotto\/aquael-set-di-gamberi-smart-dn-20\/","og_site_name":"Bluviva","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61572180581409","article_modified_time":"2025-07-24T11:28:38+00:00","og_image":[{"width":2042,"height":2042,"url":"https:\/\/bluviva.com\/wp-content\/uploads\/2025\/03\/124835-SHRIMP-SET-SMART-DN-20-CZARNY-ECOM_8.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bluviva.com\/it\/prodotto\/aquael-set-di-gamberi-smart-dn-20\/","url":"https:\/\/bluviva.com\/it\/prodotto\/aquael-set-di-gamberi-smart-dn-20\/","name":"AquaEL Set di gamberi Smart D&amp;N 20 - Bluviva","isPartOf":{"@id":"https:\/\/bluviva.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bluviva.com\/it\/prodotto\/aquael-set-di-gamberi-smart-dn-20\/#primaryimage"},"image":{"@id":"https:\/\/bluviva.com\/it\/prodotto\/aquael-set-di-gamberi-smart-dn-20\/#primaryimage"},"thumbnailUrl":"https:\/\/bluviva.com\/wp-content\/uploads\/2025\/03\/124835-SHRIMP-SET-SMART-DN-20-CZARNY-ECOM_8.webp","datePublished":"2025-03-17T18:24:18+00:00","dateModified":"2025-07-24T11:28:38+00:00","breadcrumb":{"@id":"https:\/\/bluviva.com\/it\/prodotto\/aquael-set-di-gamberi-smart-dn-20\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bluviva.com\/it\/prodotto\/aquael-set-di-gamberi-smart-dn-20\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/bluviva.com\/it\/prodotto\/aquael-set-di-gamberi-smart-dn-20\/#primaryimage","url":"https:\/\/bluviva.com\/wp-content\/uploads\/2025\/03\/124835-SHRIMP-SET-SMART-DN-20-CZARNY-ECOM_8.webp","contentUrl":"https:\/\/bluviva.com\/wp-content\/uploads\/2025\/03\/124835-SHRIMP-SET-SMART-DN-20-CZARNY-ECOM_8.webp","width":2042,"height":2042},{"@type":"BreadcrumbList","@id":"https:\/\/bluviva.com\/it\/prodotto\/aquael-set-di-gamberi-smart-dn-20\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Casa","item":"https:\/\/bluviva.com\/it\/casa\/"},{"@type":"ListItem","position":2,"name":"Negozio","item":"https:\/\/bluviva.com\/shop\/"},{"@type":"ListItem","position":3,"name":"AquaEL Set di gamberi Smart D&amp;N 20"}]},{"@type":"WebSite","@id":"https:\/\/bluviva.com\/it\/#website","url":"https:\/\/bluviva.com\/it\/","name":"Bluviva","description":"Online Aquarium Shop","publisher":{"@id":"https:\/\/bluviva.com\/it\/#organization"},"alternateName":"Bluviva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bluviva.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/bluviva.com\/it\/#organization","name":"Bluviva","url":"https:\/\/bluviva.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/bluviva.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/bluviva.com\/wp-content\/uploads\/2025\/10\/474620657_122101559012739352_4098091748390755316_n.webp","contentUrl":"https:\/\/bluviva.com\/wp-content\/uploads\/2025\/10\/474620657_122101559012739352_4098091748390755316_n.webp","width":200,"height":200,"caption":"Bluviva"},"image":{"@id":"https:\/\/bluviva.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61572180581409","https:\/\/www.youtube.com\/@Bluviva","https:\/\/www.instagram.com\/bluvivaeu\/","https:\/\/pinterest.com\/bluviva\/"]}]}},"_links":{"self":[{"href":"https:\/\/bluviva.com\/it\/wp-json\/wp\/v2\/product\/60488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bluviva.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bluviva.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/bluviva.com\/it\/wp-json\/wp\/v2\/comments?post=60488"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bluviva.com\/it\/wp-json\/wp\/v2\/media\/27219"}],"wp:attachment":[{"href":"https:\/\/bluviva.com\/it\/wp-json\/wp\/v2\/media?parent=60488"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bluviva.com\/it\/wp-json\/wp\/v2\/product_brand?post=60488"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bluviva.com\/it\/wp-json\/wp\/v2\/product_cat?post=60488"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bluviva.com\/it\/wp-json\/wp\/v2\/product_tag?post=60488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}