{"id":59510,"date":"2025-05-10T21:21:25","date_gmt":"2025-05-10T21:21:25","guid":{"rendered":"https:\/\/test.bluviva.fr\/product\/seachem-flourish-iron\/"},"modified":"2026-09-02T04:41:46","modified_gmt":"2026-09-02T04:41:46","slug":"seachem-flourish-iron","status":"publish","type":"product","link":"https:\/\/bluviva.com\/fr\/produit\/seachem-flourish-iron\/","title":{"rendered":"Seachem Flourish Iron"},"content":{"rendered":"<h2>Flourish Iron&#x2122; - Suppl\u00e9ment de fer ferreux pour des plantes aquatiques saines<\/h2>\n<h3>Description<\/h3>\n<p>Le fer est immobile dans les plantes, ce qui signifie que les plantes ne peuvent pas rediriger le fer des feuilles plus \u00e2g\u00e9es vers les nouvelles pousses. Par cons\u00e9quent, les sympt\u00f4mes de carence apparaissent d&rsquo;abord sur les feuilles plus jeunes ou nouvelles. Le fer \u00e9tant essentiel \u00e0 la production de chlorophylle, une carence en fer entra\u00eene une chlorose ou un jaunissement des jeunes feuilles. En outre, les tiges peuvent devenir courtes et minces. Si la carence est grave et prolong\u00e9e, chaque nouvelle feuille appara\u00eetra plus claire que la pr\u00e9c\u00e9dente.    <\/p>\n<h3>Comprendre les formes de fer<\/h3>\n<p>Lors du choix d&rsquo;un suppl\u00e9ment de fer, il est essentiel de comprendre la distinction entre les deux formes de fer : ferreux (charge +2) et ferrique (charge +3). Le fer ferreux est la forme pr\u00e9f\u00e9r\u00e9e des plantes car il est soluble dans l&rsquo;eau quel que soit le pH. En revanche, le fer ferrique n&rsquo;est soluble qu&rsquo;\u00e0 un pH inf\u00e9rieur \u00e0 5,5. Si le pH d\u00e9passe 5,5, ce qui est courant dans les aquariums plant\u00e9s, le fer ferrique devient insoluble, se pr\u00e9cipite et se d\u00e9pose dans la zone des racines. D\u00e8s lors, l&rsquo;absorption foliaire du fer devient impossible.    <\/p>\n<h3>D\u00e9fis pos\u00e9s par le fer-EDTA<\/h3>\n<p>Pour \u00e9viter la pr\u00e9cipitation du fer ferrique, de nombreux produits utilisent un ch\u00e9late de fer ferrique, tel que le fer-EDTA. Cette approche pr\u00e9sente toutefois deux inconv\u00e9nients pour l&rsquo;absorption foliaire du fer : <\/p>\n<ul>\n<li><strong>La liaison fer-EDTA est forte :<\/strong> cela signifie que seule une petite quantit\u00e9 de fer sera disponible pour les plantes au fil du temps.<\/li>\n<li><strong>D\u00e9pense d&rsquo;\u00e9nergie :<\/strong> Les plantes doivent d\u00e9penser de l&rsquo;\u00e9nergie pour extraire le fer de l&rsquo;EDTA et le r\u00e9duire \u00e0 la forme ferreuse avant de pouvoir l&rsquo;utiliser.<\/li>\n<\/ul>\n<h3>Approche Flourish Iron&#x2122;<\/h3>\n<p>Flourish Iron&#x2122; adopte une approche diff\u00e9rente en utilisant un complexe (et non un ch\u00e9late) de fer ferreux. Ce suppl\u00e9ment est un gluconate de fer ferreux hautement concentr\u00e9 (10 000 mg\/L), que les plantes peuvent plus facilement utiliser car il est d\u00e9j\u00e0 sous forme ferreuse. La plante n&rsquo;a donc pas besoin de d\u00e9penser de l&rsquo;\u00e9nergie pour r\u00e9duire le fer.  <\/p>\n<p>Contrairement \u00e0 ce que certains fabricants peuvent sugg\u00e9rer, le gluconate n&rsquo;est pas nocif pour les plantes ou les poissons. En fait, le gluconate ferreux convient mieux \u00e0 l&rsquo;alimentation foliaire que le fer-EDTA, car la liaison entre le fer et le gluconate est plus faible. En outre, le gluconate ferreux offre l&rsquo;avantage suppl\u00e9mentaire d&rsquo;\u00eatre une source de carbone, ce qui contribue \u00e0 la sant\u00e9 des plantes.  <\/p>\n<h3>Principaux avantages<\/h3>\n<ul>\n<li>Suppl\u00e9ment de gluconate de fer ferreux hautement concentr\u00e9 (10 000 mg\/L)<\/li>\n<li>Les plantes peuvent facilement absorber le fer ferreux sans d\u00e9penser d&rsquo;\u00e9nergie<\/li>\n<li>Le gluconate assure une liaison plus faible, ce qui permet aux plantes d&rsquo;utiliser plus facilement le fer.<\/li>\n<li>Le gluconate de fer sert \u00e9galement de source de carbone pour les plantes.<\/li>\n<li>Plus s\u00fbr pour les plantes et les poissons que le fer-EDTA<\/li>\n<\/ul>\n<h3>Instructions d&rsquo;utilisation<\/h3>\n<p>Flourish Iron&#x2122; doit \u00eatre dos\u00e9 en fonction des besoins de vos plantes aquatiques, notamment lorsque des sympt\u00f4mes de carence en fer (jaunissement des feuilles) sont observ\u00e9s. Ce suppl\u00e9ment est id\u00e9al pour fournir une forme biodisponible de fer facilement utilisable par les plantes, favorisant une croissance saine et des feuilles d&rsquo;un vert \u00e9clatant. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Flourish Iron&#x2122; - Suppl\u00e9ment de fer ferreux pour des plantes aquatiques saines Description Le fer est immobile dans les plantes, ce qui signifie que les plantes ne peuvent pas rediriger le fer des feuilles plus \u00e2g\u00e9es vers les nouvelles pousses. Par cons\u00e9quent, les sympt\u00f4mes de carence apparaissent d&rsquo;abord sur les feuilles plus jeunes ou nouvelles. [&hellip;]<\/p>\n","protected":false},"featured_media":37873,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[1878],"product_cat":[975],"product_tag":[],"class_list":["post-59510","product","type-product","status-publish","has-post-thumbnail","product_brand-seachem-es","product_cat-fertilizante-liquido-es","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Seachem Flourish Iron - Bluviva<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bluviva.com\/fr\/produit\/seachem-flourish-iron\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seachem Flourish Iron - Bluviva\" \/>\n<meta property=\"og:description\" content=\"Flourish Iron&#x2122; - Suppl\u00e9ment de fer ferreux pour des plantes aquatiques saines Description Le fer est immobile dans les plantes, ce qui signifie que les plantes ne peuvent pas rediriger le fer des feuilles plus \u00e2g\u00e9es vers les nouvelles pousses. Par cons\u00e9quent, les sympt\u00f4mes de carence apparaissent d&rsquo;abord sur les feuilles plus jeunes ou nouvelles. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bluviva.com\/fr\/produit\/seachem-flourish-iron\/\" \/>\n<meta property=\"og:site_name\" content=\"Bluviva\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61572180581409\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T04:41:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bluviva.com\/wp-content\/uploads\/2025\/05\/0476-Flourish-Iron-250-mL-2-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"683\" \/>\n\t<meta property=\"og:image:height\" content=\"2428\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bluviva.com\\\/fr\\\/produit\\\/seachem-flourish-iron\\\/\",\"url\":\"https:\\\/\\\/bluviva.com\\\/fr\\\/produit\\\/seachem-flourish-iron\\\/\",\"name\":\"Seachem Flourish Iron - Bluviva\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bluviva.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bluviva.com\\\/fr\\\/produit\\\/seachem-flourish-iron\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bluviva.com\\\/fr\\\/produit\\\/seachem-flourish-iron\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bluviva.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/0476-Flourish-Iron-250-mL-2-1.webp\",\"datePublished\":\"2025-05-10T21:21:25+00:00\",\"dateModified\":\"2026-09-02T04:41:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bluviva.com\\\/fr\\\/produit\\\/seachem-flourish-iron\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bluviva.com\\\/fr\\\/produit\\\/seachem-flourish-iron\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/bluviva.com\\\/fr\\\/produit\\\/seachem-flourish-iron\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bluviva.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/0476-Flourish-Iron-250-mL-2-1.webp\",\"contentUrl\":\"https:\\\/\\\/bluviva.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/0476-Flourish-Iron-250-mL-2-1.webp\",\"width\":683,\"height\":2428},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bluviva.com\\\/fr\\\/produit\\\/seachem-flourish-iron\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/bluviva.com\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/bluviva.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Seachem Flourish Iron\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bluviva.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/bluviva.com\\\/fr\\\/\",\"name\":\"Bluviva\",\"description\":\"Online Aquarium Shop\",\"publisher\":{\"@id\":\"https:\\\/\\\/bluviva.com\\\/fr\\\/#organization\"},\"alternateName\":\"Bluviva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bluviva.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bluviva.com\\\/fr\\\/#organization\",\"name\":\"Bluviva\",\"url\":\"https:\\\/\\\/bluviva.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/bluviva.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bluviva.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/474620657_122101559012739352_4098091748390755316_n.webp\",\"contentUrl\":\"https:\\\/\\\/bluviva.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/474620657_122101559012739352_4098091748390755316_n.webp\",\"width\":200,\"height\":200,\"caption\":\"Bluviva\"},\"image\":{\"@id\":\"https:\\\/\\\/bluviva.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61572180581409\",\"https:\\\/\\\/www.youtube.com\\\/@Bluviva\",\"https:\\\/\\\/www.instagram.com\\\/bluvivaeu\\\/\",\"https:\\\/\\\/pinterest.com\\\/bluviva\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Seachem Flourish Iron - Bluviva","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bluviva.com\/fr\/produit\/seachem-flourish-iron\/","og_locale":"fr_FR","og_type":"article","og_title":"Seachem Flourish Iron - Bluviva","og_description":"Flourish Iron&#x2122; - Suppl\u00e9ment de fer ferreux pour des plantes aquatiques saines Description Le fer est immobile dans les plantes, ce qui signifie que les plantes ne peuvent pas rediriger le fer des feuilles plus \u00e2g\u00e9es vers les nouvelles pousses. Par cons\u00e9quent, les sympt\u00f4mes de carence apparaissent d&rsquo;abord sur les feuilles plus jeunes ou nouvelles. [&hellip;]","og_url":"https:\/\/bluviva.com\/fr\/produit\/seachem-flourish-iron\/","og_site_name":"Bluviva","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61572180581409","article_modified_time":"2026-09-02T04:41:46+00:00","og_image":[{"width":683,"height":2428,"url":"https:\/\/bluviva.com\/wp-content\/uploads\/2025\/05\/0476-Flourish-Iron-250-mL-2-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bluviva.com\/fr\/produit\/seachem-flourish-iron\/","url":"https:\/\/bluviva.com\/fr\/produit\/seachem-flourish-iron\/","name":"Seachem Flourish Iron - Bluviva","isPartOf":{"@id":"https:\/\/bluviva.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bluviva.com\/fr\/produit\/seachem-flourish-iron\/#primaryimage"},"image":{"@id":"https:\/\/bluviva.com\/fr\/produit\/seachem-flourish-iron\/#primaryimage"},"thumbnailUrl":"https:\/\/bluviva.com\/wp-content\/uploads\/2025\/05\/0476-Flourish-Iron-250-mL-2-1.webp","datePublished":"2025-05-10T21:21:25+00:00","dateModified":"2026-09-02T04:41:46+00:00","breadcrumb":{"@id":"https:\/\/bluviva.com\/fr\/produit\/seachem-flourish-iron\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bluviva.com\/fr\/produit\/seachem-flourish-iron\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/bluviva.com\/fr\/produit\/seachem-flourish-iron\/#primaryimage","url":"https:\/\/bluviva.com\/wp-content\/uploads\/2025\/05\/0476-Flourish-Iron-250-mL-2-1.webp","contentUrl":"https:\/\/bluviva.com\/wp-content\/uploads\/2025\/05\/0476-Flourish-Iron-250-mL-2-1.webp","width":683,"height":2428},{"@type":"BreadcrumbList","@id":"https:\/\/bluviva.com\/fr\/produit\/seachem-flourish-iron\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/bluviva.com\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/bluviva.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Seachem Flourish Iron"}]},{"@type":"WebSite","@id":"https:\/\/bluviva.com\/fr\/#website","url":"https:\/\/bluviva.com\/fr\/","name":"Bluviva","description":"Online Aquarium Shop","publisher":{"@id":"https:\/\/bluviva.com\/fr\/#organization"},"alternateName":"Bluviva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bluviva.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/bluviva.com\/fr\/#organization","name":"Bluviva","url":"https:\/\/bluviva.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/bluviva.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/bluviva.com\/wp-content\/uploads\/2025\/10\/474620657_122101559012739352_4098091748390755316_n.webp","contentUrl":"https:\/\/bluviva.com\/wp-content\/uploads\/2025\/10\/474620657_122101559012739352_4098091748390755316_n.webp","width":200,"height":200,"caption":"Bluviva"},"image":{"@id":"https:\/\/bluviva.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61572180581409","https:\/\/www.youtube.com\/@Bluviva","https:\/\/www.instagram.com\/bluvivaeu\/","https:\/\/pinterest.com\/bluviva\/"]}]}},"_links":{"self":[{"href":"https:\/\/bluviva.com\/fr\/wp-json\/wp\/v2\/product\/59510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bluviva.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bluviva.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/bluviva.com\/fr\/wp-json\/wp\/v2\/comments?post=59510"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bluviva.com\/fr\/wp-json\/wp\/v2\/media\/37873"}],"wp:attachment":[{"href":"https:\/\/bluviva.com\/fr\/wp-json\/wp\/v2\/media?parent=59510"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bluviva.com\/fr\/wp-json\/wp\/v2\/product_brand?post=59510"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bluviva.com\/fr\/wp-json\/wp\/v2\/product_cat?post=59510"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bluviva.com\/fr\/wp-json\/wp\/v2\/product_tag?post=59510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}