{"id":69242,"date":"2026-02-13T17:54:24","date_gmt":"2026-02-13T17:54:24","guid":{"rendered":"https:\/\/bluviva.com\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\/"},"modified":"2026-04-21T20:33:16","modified_gmt":"2026-04-21T20:33:16","slug":"5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt","status":"publish","type":"post","link":"https:\/\/bluviva.com\/de\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\/","title":{"rendered":"5 H\u00e4ufige Krankheiten bei Aquarienfischen (und wie man sie schnell und sicher behandelt)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Fische k\u00f6nnen krank werden, selbst wenn ihr Aquarium sehr sauber und ordentlich gehalten wird.<\/p>\n\n<p class=\"wp-block-paragraph\">Im Allgemeinen sind Krankheiten nichts, wof\u00fcr Fische pl\u00f6tzlich anf\u00e4llig werden k\u00f6nnen. <strong>K\u00f6rperliche Symptome und Verhaltens\u00e4nderungen <\/strong>beginnen meist so subtil, dass man sie leicht \u00fcbersehen kann, vor allem, wenn man Anf\u00e4nger ist. Ein winziger wei\u00dfer Punkt. Eine leicht eingerissene Flosse. Ein Fisch, der sich nicht mehr der Gruppe anschlie\u00dft.   <\/p>\n\n<p class=\"wp-block-paragraph\">Wenn Sie verstehen, was Sie sehen, und wenn Sie fr\u00fch damit anfangen, ist das ein gro\u00dfer Unterschied.<\/p>\n\n<p class=\"wp-block-paragraph\">In diesem Tutorial werden die <strong>5 h\u00e4ufigsten Fischkrankheiten in Aquarien<\/strong> aufgeschl\u00fcsselt: ihre Erkennungsmerkmale, die Faktoren, die zu ihnen f\u00fchren, und die M\u00f6glichkeiten, wie Sie Ihre Fische sicher und erfolgreich behandeln k\u00f6nnen<strong>, ohne Ihre Pflanzen oder n\u00fctzlichen Bakterien zu sch\u00e4digen.<\/strong><\/p>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n<h2 class=\"wp-block-heading\">Warum werden Aquarienfische krank?<\/h2>\n\n<p class=\"wp-block-paragraph\">Fische sind ein Teil eines <strong>geschlossenen \u00d6kosystems<\/strong>. Anders als in freier Wildbahn k\u00f6nnen sie Krankheitserregern oder schlechten Wasserbedingungen nicht entkommen. <\/p>\n\n<p class=\"wp-block-paragraph\">Krankheiten treten in der Regel dann auf, wenn das Immunsystem eines Fisches geschw\u00e4cht ist, z. B. durch:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Schlechte Wasserqualit\u00e4t<\/strong> (Ammoniak, Nitrit, instabiler pH-Wert)<\/li>\n\n\n\n<li><strong>Unerwartete Temperaturschwankungen<\/strong><\/li>\n\n\n\n<li>Enge und Stress aufgrund von \u00dcberbelegung oder Mobbing<\/li>\n\n\n\n<li>Neue Fische werden <strong>ohne vorherige Quarant\u00e4ne<\/strong> eingebracht<\/li>\n\n\n\n<li>Unzureichende Ern\u00e4hrung<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">In den meisten Aquarien sind Bakterien oder Parasiten in der Regel in sehr geringer Zahl vorhanden.  <strong>Gesunde Fische widerstehen ihnen. Gestresste Fische k\u00f6nnen das oft nicht. <\/strong><\/p>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n<h2 class=\"wp-block-heading\">Die 5 wichtigsten Krankheitsanzeichen (und was sie bedeuten)<\/h2>\n\n<h3 class=\"wp-block-heading\">1. Wei\u00dffleckenkrankheit (Ich) - Kleine wei\u00dfe Punkte auf K\u00f6rper und Flossen<\/h3>\n\n<p class=\"wp-block-paragraph\">Die bekannteste und h\u00e4ufigste Krankheit in der Aquaristik ist <strong>Ichthyophthirius multifiliis<\/strong>, gemeinhin bekannt als Wei\u00dfp\u00fcnktchen oder Ich.<\/p>\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><a href=\"https:\/\/bluviva.com\/de\/produkt\/esha-beenden\/\"><img decoding=\"async\" width=\"1024\" height=\"657\" src=\"https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Weispunktchenkrankheit-1024x657.webp\" alt=\"\" class=\"wp-image-69164\" style=\"aspect-ratio:1.558610239203377;width:350px;height:auto\" srcset=\"https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Weispunktchenkrankheit-1024x657.webp 1024w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Weispunktchenkrankheit-300x192.webp 300w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Weispunktchenkrankheit-768x493.webp 768w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Weispunktchenkrankheit-990x635.webp 990w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Weispunktchenkrankheit-441x283.webp 441w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Weispunktchenkrankheit-800x513.webp 800w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Weispunktchenkrankheit-150x96.webp 150w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Weispunktchenkrankheit.webp 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Fische mit Wei\u00dfp\u00fcnktchenkrankheit (Ichthyophthiriasis)<\/figcaption><\/figure>\n\n<h4 class=\"wp-block-heading\">Wie diese Fischkrankheit aussieht:<\/h4>\n\n<p class=\"wp-block-paragraph\">Winzige wei\u00dfe K\u00f6rner, die wie Salz oder Zucker aussehen, sind auf Flossen und K\u00f6rper verstreut.<\/p>\n\n<h4 class=\"wp-block-heading\">Fr\u00fche Warnzeichen:<\/h4>\n\n<ul class=\"wp-block-list\">\n<li>Fische, die sich an Felsen oder Substrat reiben (&#8220;Flashen&#8220;)<\/li>\n\n\n\n<li>Appetitlosigkeit<\/li>\n\n\n\n<li>Vermehrtes Verstecken<\/li>\n<\/ul>\n\n<h4 class=\"wp-block-heading\">Warum Whitespot gef\u00e4hrlich ist:<\/h4>\n\n<p class=\"wp-block-paragraph\">Sie bef\u00e4llt sowohl die Haut als auch die Kiemen, was sie hoch ansteckend macht und die Atmung beeintr\u00e4chtigen kann.<\/p>\n\n<h4 class=\"wp-block-heading\">Wie man Wei\u00dfflecken behandelt:<\/h4>\n\n<p class=\"wp-block-paragraph\">Behandeln Sie mit einem speziellen Medikament gegen Parasiten wie z.B. <strong><a href=\"https:\/\/bluviva.com\/de\/produkt\/esha-beenden\/\" id=\"https:\/\/bluviva.com\/product\/esha-exit\/\">eSHa EXIT<\/a><\/strong>. Eine leichte Erh\u00f6hung der Wassertemperatur, wenn die Art es zul\u00e4sst, kann den Lebenszyklus der Parasiten beschleunigen und somit eine wirksamere Behandlung erm\u00f6glichen. <\/p>\n\n<hr class=\"wp-block-separator has-text-color has-cyan-bluish-gray-color has-alpha-channel-opacity has-cyan-bluish-gray-background-color has-background is-style-default\"\/>\n\n<h3 class=\"wp-block-heading\">2. Flossenf\u00e4ule - ausgefranste oder sich verschlechternde Flossen<\/h3>\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><a href=\"https:\/\/bluviva.com\/de\/produkt\/esha-2000\/\"><img decoding=\"async\" width=\"1024\" height=\"963\" src=\"https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Fin_Rot_on_Betta_Fish-1024x963.webp\" alt=\"\" class=\"wp-image-69176\" style=\"width:350px\" srcset=\"https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Fin_Rot_on_Betta_Fish-1024x963.webp 1024w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Fin_Rot_on_Betta_Fish-300x282.webp 300w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Fin_Rot_on_Betta_Fish-768x722.webp 768w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Fin_Rot_on_Betta_Fish-990x931.webp 990w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Fin_Rot_on_Betta_Fish-441x415.webp 441w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Fin_Rot_on_Betta_Fish-800x753.webp 800w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Fin_Rot_on_Betta_Fish-150x141.webp 150w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Fin_Rot_on_Betta_Fish.webp 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Betta Fische mit Flossenf\u00e4ule (besch\u00e4digte Flossen)<\/figcaption><\/figure>\n\n<h4 class=\"wp-block-heading\">Wie diese Fischkrankheit aussieht:<\/h4>\n\n<p class=\"wp-block-paragraph\">Die Flossen erscheinen <strong>ausgefranst, zerrissen oder verk\u00fcrzt.<\/strong> Die R\u00e4nder k\u00f6nnen wei\u00df oder rot werden.<\/p>\n\n<h4 class=\"wp-block-heading\">H\u00e4ufige Ursachen f\u00fcr Flossenf\u00e4ule:<\/h4>\n\n<p class=\"wp-block-paragraph\">In der Regel eine <strong>bakterielle Infektion<\/strong>, die oft durch schlechte Wasserqualit\u00e4t oder Verletzungen verursacht wird.<\/p>\n\n<h4 class=\"wp-block-heading\">Warum eine schnelle Behandlung wichtig ist:<\/h4>\n\n<p class=\"wp-block-paragraph\">Wenn sie nicht behandelt wird, kann sich die Infektion weiter in Richtung Flossenansatz ausbreiten und <strong>lebensbedrohlich<\/strong> werden.<\/p>\n\n<h4 class=\"wp-block-heading\">Wie man Flossenf\u00e4ule behandelt:<\/h4>\n\n<p class=\"wp-block-paragraph\"><strong>F\u00fchren Sie zun\u00e4chst<\/strong> einen <strong>Wasserwechsel von 30-50% durch<\/strong> und geben Sie anschlie\u00dfend ein antibakterielles Breitbandmedikament wie <strong><a href=\"https:\/\/bluviva.com\/de\/produkt\/esha-2000\/\">eSHa 2000<\/a><\/strong>. Die Aktivkohle sollte w\u00e4hrend der Behandlung entfernt werden. <\/p>\n\n<hr class=\"wp-block-separator has-text-color has-cyan-bluish-gray-color has-alpha-channel-opacity has-cyan-bluish-gray-background-color has-background is-style-default\"\/>\n\n<h3 class=\"wp-block-heading\">3. Velvet Disease - Feiner gold- oder rostfarbener Staub<\/h3>\n\n<p class=\"wp-block-paragraph\">Oft mit dem Wei\u00dffleck verwechselt, ist Velvet (Oodinium) kleiner und gef\u00e4hrlicher.<\/p>\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><a href=\"https:\/\/bluviva.com\/de\/produkt\/esha-beenden\/\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/1280px-Velvet_infection-1024x768.webp\" alt=\"\" class=\"wp-image-69170\" style=\"width:350px\" srcset=\"https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/1280px-Velvet_infection-1024x768.webp 1024w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/1280px-Velvet_infection-300x225.webp 300w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/1280px-Velvet_infection-768x576.webp 768w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/1280px-Velvet_infection-990x743.webp 990w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/1280px-Velvet_infection-441x331.webp 441w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/1280px-Velvet_infection-800x600.webp 800w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/1280px-Velvet_infection-150x113.webp 150w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/1280px-Velvet_infection.webp 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Von der Samtkrankheit befallene Fische (goldener Staub auf der Haut)<\/figcaption><\/figure>\n\n<h4 class=\"wp-block-heading\">Wie die Samtfischkrankheit aussieht:<\/h4>\n\n<p class=\"wp-block-paragraph\">Die Haut erscheint mit <strong>feinem gold- oder rostfarbenem Staub<\/strong> bedeckt <strong>.<\/strong> Die Fische k\u00f6nnen leicht matt oder lethargisch aussehen.<\/p>\n\n<h4 class=\"wp-block-heading\">Schl\u00fcsselsymptome:<\/h4>\n\n<ul class=\"wp-block-list\">\n<li>Eingeklemmte Flossen<\/li>\n\n\n\n<li>Schnelles Atmen<\/li>\n\n\n\n<li>Bleiben Sie in der N\u00e4he des Filterausflusses<\/li>\n<\/ul>\n\n<h4 class=\"wp-block-heading\">Warum es ernst ist:<\/h4>\n\n<p class=\"wp-block-paragraph\">Velvet greift auch <strong>fr\u00fchzeitig<\/strong> die <strong>Kiemen<\/strong> an, was die Atmungsf\u00e4higkeit beeintr\u00e4chtigen kann.<\/p>\n\n<h4 class=\"wp-block-heading\">Wie man die Samtfischkrankheit behandelt:<\/h4>\n\n<p class=\"wp-block-paragraph\">Verwenden Sie ein Antiparasitikum wie <strong><a href=\"https:\/\/bluviva.com\/de\/produkt\/esha-beenden\/\" id=\"https:\/\/bluviva.com\/product\/esha-exit\/\">eSHa EXIT<\/a><\/strong> und dimmen Sie das Licht w\u00e4hrend der Behandlung, da der Parasit teilweise auf Licht angewiesen ist.<\/p>\n\n<hr class=\"wp-block-separator has-text-color has-cyan-bluish-gray-color has-alpha-channel-opacity has-cyan-bluish-gray-background-color has-background is-style-default\"\/>\n\n<h3 class=\"wp-block-heading\">4. Innere Parasiten und Lochkrankheit (h\u00e4ufig bei Diskus und Cichliden)<\/h3>\n\n<p class=\"wp-block-paragraph\">Nicht alle Krankheiten sind auf der Haut sichtbar. Innere Parasiten sind stille Killer. <\/p>\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><a href=\"https:\/\/bluviva.com\/de\/produkt\/esha-gdex\/\"><img decoding=\"async\" width=\"500\" height=\"633\" src=\"https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Henneguya_zschokkei.webp\" alt=\"\" class=\"wp-image-69182\" style=\"width:350px\" srcset=\"https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Henneguya_zschokkei.webp 500w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Henneguya_zschokkei-237x300.webp 237w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Henneguya_zschokkei-441x558.webp 441w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Henneguya_zschokkei-300x380.webp 300w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Henneguya_zschokkei-150x190.webp 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><figcaption class=\"wp-element-caption\">Fische mit inneren Parasiten<\/figcaption><\/figure>\n\n<h4 class=\"wp-block-heading\">Wie diese Fischkrankheit aussieht:<\/h4>\n\n<p class=\"wp-block-paragraph\">Die Fische k\u00f6nnen <strong>trotz normaler Nahrungsaufnahme d\u00fcnn<\/strong> werden und mit der Zeit einen <strong>eingefallenen oder hohlen Bauch<\/strong> entwickeln. Ein sehr h\u00e4ufiges Fr\u00fchwarnzeichen ist <strong>langer, wei\u00dfer, fadenf\u00f6rmiger Kot<\/strong>. <\/p>\n\n<p class=\"wp-block-paragraph\">Bei Buntbarschen wie <strong>Diskus und Skalaren<\/strong> k\u00f6nnen fortgeschrittene Krankheiten die <strong>Hole-in-the-Head-Krankheit<\/strong> verursachen, bei der kleine Vertiefungen am Kopf und entlang der Seitenlinie entstehen.<\/p>\n\n<h4 class=\"wp-block-heading\">Wodurch wird sie verursacht?<\/h4>\n\n<p class=\"wp-block-paragraph\">Die Hole-in-the-Head-Krankheit ist ein <strong>multifaktorieller<\/strong> Prozess, der eng mit verschiedenen inneren Protozoenparasiten wie <strong>Hexamita (Spironucleus)<\/strong> zusammenh\u00e4ngt. Der Parasit selbst ist jedoch nicht immer die alleinige Ursache. <\/p>\n\n<p class=\"wp-block-paragraph\">Ausbr\u00fcche sind in der Regel verbunden mit:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Chronischer Stress<\/strong><\/li>\n\n\n\n<li><strong>Schlechte Wasserqualit\u00e4t<\/strong><\/li>\n\n\n\n<li>Ern\u00e4hrungsbedingte Defizite<\/li>\n\n\n\n<li>Geschw\u00e4chtes Immunsystem<\/li>\n\n\n\n<li>Wild gefangener Fisch oder k\u00fcrzlich importierter Fisch<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Einige Fischarten k\u00f6nnen in geringem Ma\u00dfe mit der Protozoen-Krankheit Hexamita infiziert sein, ohne dass es Anzeichen der Krankheit gibt. Die Krankheit wird ausgel\u00f6st, wenn die Immunabwehr des Fisches geschw\u00e4cht ist. <\/p>\n\n<h4 class=\"wp-block-heading\">Warum eine fr\u00fche Behandlung wichtig ist:<\/h4>\n\n<p class=\"wp-block-paragraph\">Innere Infektionen schreiten oft langsam voran, aber der Zustand kann schwerwiegend werden. Da die N\u00e4hrstoffe nicht mehr absorbiert werden, wird der Fisch geschw\u00e4cht, was die Genesung erschwert. <\/p>\n\n<p class=\"wp-block-paragraph\">Sobald sichtbare L\u00e4sionen am Kopf auftreten, ist die Krankheit bereits fortgeschritten. Wenn Sie also bereits im Stadium des <strong>Gewichtsverlusts und des abnormen Stuhlgangs<\/strong> handeln, verbessern sich die Erfolgsquoten erheblich.<\/p>\n\n<h4 class=\"wp-block-heading\">Wie Sie die Hole-in-the-Head-Krankheit behandeln:<\/h4>\n\n<p class=\"wp-block-paragraph\"><strong>Interne Infektionen k\u00f6nnen sich schnell verschlimmern, wenn sie ignoriert werden.<\/strong>  Eine fr\u00fchzeitige Behandlung ist entscheidend.<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Hexamita &amp; Hole-in-the-Head (Diskus, Skalare):<\/strong> Verwendung <a href=\"https:\/\/bluviva.com\/de\/produkt\/esha-hexamita\/\"><strong>eSHa HEXAMITA<\/strong><\/a>, eine spezielle Fischformel, die f\u00fcr die meisten tropischen und Kaltwasserfischarten verwendet werden kann. Kann pr\u00e4ventiv bei Hochrisikospezies und in Kombination mit <strong>eSHa Gdex<\/strong> verwendet werden <strong>.<\/strong> <\/li>\n\n\n\n<li><strong>W\u00fcrmer &amp; Plattw\u00fcrmer<\/strong>: <a href=\"https:\/\/bluviva.com\/de\/produkt\/esha-gdex\/\"><strong>Verwenden Sie eSHa Gdex<\/strong><\/a>das sicher und wirksam gegen innere Parasiten wie Plattw\u00fcrmer, Kiemenw\u00fcrmer und Bandw\u00fcrmer ist, ohne Pflanzen, Garnelen und n\u00fctzliche Bakterien zu sch\u00e4digen.<\/li>\n<\/ul>\n\n<hr class=\"wp-block-separator has-text-color has-cyan-bluish-gray-color has-alpha-channel-opacity has-cyan-bluish-gray-background-color has-background is-style-default\"\/>\n\n<h3 class=\"wp-block-heading\">5. Kiemenfl\u00f6he - Atemprobleme bei normalen Wasserparametern<\/h3>\n\n<p class=\"wp-block-paragraph\">Wenn die Wasserparameter perfekt sind (kein Ammoniak), aber die Fische an der Oberfl\u00e4che nach Luft schnappen, vermuten Sie Kiemenw\u00fcrmer.<\/p>\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><a href=\"https:\/\/bluviva.com\/de\/produkt\/esha-gdex\/\"><img decoding=\"async\" width=\"1024\" height=\"792\" src=\"https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/FMIB_41566_Young_Brook_Trout_Diseased-Gill_of_Large_Fish_with_Copepod_Parasites.jpeg-1024x792.webp\" alt=\"\" class=\"wp-image-69188\" style=\"width:350px\" srcset=\"https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/FMIB_41566_Young_Brook_Trout_Diseased-Gill_of_Large_Fish_with_Copepod_Parasites.jpeg-1024x792.webp 1024w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/FMIB_41566_Young_Brook_Trout_Diseased-Gill_of_Large_Fish_with_Copepod_Parasites.jpeg-300x232.webp 300w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/FMIB_41566_Young_Brook_Trout_Diseased-Gill_of_Large_Fish_with_Copepod_Parasites.jpeg-768x594.webp 768w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/FMIB_41566_Young_Brook_Trout_Diseased-Gill_of_Large_Fish_with_Copepod_Parasites.jpeg-990x766.webp 990w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/FMIB_41566_Young_Brook_Trout_Diseased-Gill_of_Large_Fish_with_Copepod_Parasites.jpeg-441x341.webp 441w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/FMIB_41566_Young_Brook_Trout_Diseased-Gill_of_Large_Fish_with_Copepod_Parasites.jpeg-800x619.webp 800w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/FMIB_41566_Young_Brook_Trout_Diseased-Gill_of_Large_Fish_with_Copepod_Parasites.jpeg-150x116.webp 150w, https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/FMIB_41566_Young_Brook_Trout_Diseased-Gill_of_Large_Fish_with_Copepod_Parasites.jpeg.webp 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Jungfische mit Kiemenflossen (besch\u00e4digte Kiemen)<\/figcaption><\/figure>\n\n<h4 class=\"wp-block-heading\">Wie diese Fischkrankheit aussieht:<\/h4>\n\n<p class=\"wp-block-paragraph\">Rote oder entz\u00fcndete Kiemen. Ein Kiemendeckel bewegt sich m\u00f6glicherweise mehr als der andere. <\/p>\n\n<h4 class=\"wp-block-heading\">Ein wichtiger Unterschied:<\/h4>\n\n<p class=\"wp-block-paragraph\">Wenn die Fische nach Luft schnappen, <strong>Ammoniak und Nitrit<\/strong> aber <strong>0 ppm betragen<\/strong>, sind Parasiten wie Kiemenw\u00fcrmer sehr wahrscheinlich.<\/p>\n\n<h4 class=\"wp-block-heading\">Warum schnelles Handeln entscheidend ist:<\/h4>\n\n<p class=\"wp-block-paragraph\">Eine verringerte Sauerstoffaufnahme aufgrund von Kiemensch\u00e4den <strong>kann t\u00f6dlich sein, wenn sie nicht behandelt wird<\/strong>.<\/p>\n\n<h4 class=\"wp-block-heading\">Wie man Kiemenw\u00fcrmer behandelt:<\/h4>\n\n<p class=\"wp-block-paragraph\">Verwenden Sie <strong><a href=\"https:\/\/bluviva.com\/de\/produkt\/esha-gdex\/\">eSHa Gdex<\/a><\/strong>, das gegen Kiemen- und Hautw\u00fcrmer wirksam und f\u00fcr Garnelen sicher ist.<\/p>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n<h2 class=\"wp-block-heading\">Schneller Aktionsplan: Was Sie sofort tun sollten<\/h2>\n\n<p class=\"wp-block-paragraph\">Wenn Sie Symptome bemerken, gehen Sie ruhig und strukturiert vor:<\/p>\n\n<h3 class=\"wp-block-heading\">Schritt 1: Wasserparameter testen<\/h3>\n\n<p class=\"wp-block-paragraph\">Verd\u00e4chtigen Sie immer <strong>zuerst Ammoniak- und Nitritspitzen<\/strong>. Die Wasserqualit\u00e4t kann manchmal einer Krankheit \u00e4hneln. <\/p>\n\n<h3 class=\"wp-block-heading\">Schritt 2: F\u00fchren Sie einen teilweisen Wasserwechsel durch<\/h3>\n\n<p class=\"wp-block-paragraph\">Ein <strong>Wasserwechsel von 30-50%<\/strong> reduziert den Stress und verbessert die Wirksamkeit der Medikamente.<\/p>\n\n<h3 class=\"wp-block-heading\">Schritt 3: Entfernen des chemischen Filtermediums<\/h3>\n\n<p class=\"wp-block-paragraph\">Aktivkohle und Harze, die Medikamente absorbieren k\u00f6nnen, sollten entfernt werden.<\/p>\n\n<h3 class=\"wp-block-heading\">Schritt 4: Pr\u00e4zise dosieren<\/h3>\n\n<p class=\"wp-block-paragraph\">Sie m\u00fcssen die Anweisungen des Herstellers sorgf\u00e4ltig befolgen. Die meisten Behandlungen dauern <strong>3 aufeinanderfolgende Tage<\/strong>. <\/p>\n\n<h3 class=\"wp-block-heading\">Schritt 5: Genaue \u00dcberwachung<\/h3>\n\n<p class=\"wp-block-paragraph\">Achten Sie auf Ver\u00e4nderungen bei der Atmung, beim Schwimmen und bei der Bildung von L\u00e4sionen. Vermeiden Sie w\u00e4hrend der Behandlung eine starke F\u00fctterung. <\/p>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n<h2 class=\"wp-block-heading\">K\u00f6nnen Behandlungen miteinander kombiniert werden?<\/h2>\n\n<p class=\"wp-block-paragraph\">Einige Medikamente, wie <strong><a href=\"https:\/\/bluviva.com\/de\/produkt\/esha-2000\/\">eSHa 2000<\/a> und <a href=\"https:\/\/bluviva.com\/de\/produkt\/esha-beenden\/\">eSHa EXIT<\/a><\/strong>, sind f\u00fcr die gemeinsame Anwendung konzipiert. Dies ist n\u00fctzlich, wenn Parasiten <strong>sekund\u00e4re bakterielle Infektionen<\/strong> verursachen. <\/p>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8d39b2df wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><a href=\"https:\/\/bluviva.com\/de\/produkt\/esha-2000\/\"><img decoding=\"async\" src=\"https:\/\/bluviva.com\/wp-content\/uploads\/2025\/05\/2000-CZ-2024@1.0x-1.webp\" alt=\"\" style=\"width:352px\"\/><\/a><figcaption class=\"wp-element-caption\">Produkt zur Behandlung von Flossenf\u00e4ule<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><a href=\"https:\/\/bluviva.com\/de\/produkt\/esha-beenden\/\"><img decoding=\"async\" src=\"https:\/\/bluviva.com\/wp-content\/uploads\/2025\/05\/EXIT-CZ-2@1.0x.webp\" alt=\"\" style=\"width:350px\"\/><\/a><figcaption class=\"wp-element-caption\">Mittel zur Behandlung der Wei\u00dfp\u00fcnktchenkrankheit und der Samtkrankheit<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n<p class=\"wp-block-paragraph\">Vermeiden Sie es, beliebige Marken zu mischen, ohne vorher die Kompatibilit\u00e4t zu pr\u00fcfen.<\/p>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n<h2 class=\"wp-block-heading\">H\u00e4ufig gestellte Fragen (FAQ) zu Fischkrankheiten<\/h2>\n\n<p class=\"wp-block-paragraph\"><strong>F: Muss ich kranke Fische unter Quarant\u00e4ne stellen?<\/strong> <strong>A:<\/strong> Wenn m\u00f6glich, ja. Ein <strong>Krankenhausbecken<\/strong> verhindert die Ausbreitung und erm\u00f6glicht eine kontrolliertere Behandlung. Hochansteckende Krankheiten wie die Ich erfordern jedoch oft eine Behandlung des <strong>gesamten Schaubeckens<\/strong>.  <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>F: Sind diese Medikamente sicher f\u00fcr Pflanzen?<\/strong> <strong>A:<\/strong> Die meisten modernen Behandlungen sind <strong>bei richtiger Anwendung pflanzenvertr\u00e4glich<\/strong>. Lesen Sie vor der Verabreichung immer das Etikett. <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>F: Meine Fische haben nach 3 Tagen immer noch Flecken. Was kann ich tun? <\/strong> <strong>A:<\/strong> Bei hartn\u00e4ckigem Wei\u00dfp\u00fcnktchenbefall (insbesondere bei niedrigeren Temperaturen) ist der Lebenszyklus des Parasiten langsamer. Sie k\u00f6nnen die Behandlung mit eSHa EXIT noch ein paar Tage verl\u00e4ngern, bis die Flecken verschwinden. <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>F: Werden Medikamente n\u00fctzliche Bakterien abt\u00f6ten?<\/strong> <strong>A:<\/strong> Qualit\u00e4tsbehandlungen wie <strong>eSHa 2000 und EXIT<\/strong> sind so formuliert, dass sie <strong>n\u00fctzliche Filterbakterien<\/strong> schonen, so dass Sie Ihren Stickstoffkreislauf normalerweise nicht neu starten m\u00fcssen.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>F: Wie kann ich Fischkrankheiten vorbeugen?<\/strong> <strong>A:<\/strong> Stellen Sie neue Fische f\u00fcr <strong>2-3 Wochen<\/strong> in Quarant\u00e4ne; sorgen Sie f\u00fcr <strong>stabile Wasserparameter<\/strong>; f\u00fchren Sie regelm\u00e4\u00dfige Wasserwechsel durch; f\u00fcttern Sie ein <strong>abwechslungsreiches, hochwertiges Futter<\/strong>; vermeiden Sie eine \u00dcberbev\u00f6lkerung. <strong>Wichtig: <\/strong>Vorbeugung ist immer einfacher und billiger als Behandlung.<\/p>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n<h2 class=\"wp-block-heading\">Letzte \u00dcberlegungen<\/h2>\n\n<p class=\"wp-block-paragraph\">Das Erste und Wichtigste bei der Haltung von Fischen ist die Beobachtung. Selbst kleine Ver\u00e4nderungen k\u00f6nnen wichtige Hinweise sein. <\/p>\n\n<p class=\"wp-block-paragraph\">Daher k\u00f6nnen die meisten h\u00e4ufigen Krankheiten durch eine fr\u00fchzeitige Erkennung und rechtzeitige Behandlung mit den richtigen Medikamenten <strong>vollst\u00e4ndig kontrolliert<\/strong> werden.<\/p>\n\n<p class=\"wp-block-paragraph\">Gesunde Aquarien basieren auf Best\u00e4ndigkeit, Stabilit\u00e4t und \u00fcberlegtem Handeln.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Warten Sie nicht, bis es zu sp\u00e4t ist.<\/strong>  Wenn Sie ein Zeichen sehen, behandeln Sie es. Eine schnelle Reaktion mit dem richtigen Produkt kann Ihren gesamten Tank retten. <\/p>\n\n<p class=\"wp-block-paragraph\"><em>Haftungsausschluss: Lesen Sie das Etikett und die Produktanweisungen vor dem Gebrauch immer sorgf\u00e4ltig durch.<\/em><\/p>\n\n<h3 class=\"wp-block-heading\">Bildnachweis:<\/h3>\n\n<ul class=\"wp-block-list\">\n<li>Fisch mit Wei\u00dfp\u00fcnktchenkrankheit (Ichthyophthiriasis) - <a href=\"https:\/\/commons.wikimedia.org\/wiki\/File:Wei%C3%9Fp%C3%BCnktchenkrankheit.jpg\">Wikimedia Commons<\/a><\/li>\n\n\n\n<li>Betta-Fisch mit Flossenf\u00e4ule (gesch\u00e4digte Flossen) - <a href=\"https:\/\/commons.wikimedia.org\/wiki\/File:Fin_Rot_on_Betta_Fish.jpg\">Wikimedia Commons<\/a><\/li>\n\n\n\n<li>Von der Samtkrankheit betroffener Fisch (goldener Staub auf der Haut) - <a href=\"https:\/\/commons.wikimedia.org\/wiki\/File:Velvet_infection.JPG\">Wikimedia Commons<\/a><\/li>\n\n\n\n<li>Fisch mit inneren Parasiten - <a href=\"https:\/\/commons.wikimedia.org\/wiki\/File:Henneguya_zschokkei.jpg\">Wikimedia Commons<\/a><\/li>\n\n\n\n<li>Jungfisch mit Kiemenflossen (besch\u00e4digte Kiemen) - <a href=\"https:\/\/commons.wikimedia.org\/wiki\/File:FMIB_41566_Young_Brook_Trout,_Diseased--Gill_of_Large_Fish_with_Copepod_Parasites.jpeg\">Wikimedia Commons<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Fische k\u00f6nnen krank werden, selbst wenn ihr Aquarium sehr sauber und ordentlich gehalten wird. Im Allgemeinen sind Krankheiten nichts, wof\u00fcr Fische pl\u00f6tzlich anf\u00e4llig werden k\u00f6nnen. K\u00f6rperliche Symptome und Verhaltens\u00e4nderungen beginnen meist so subtil, dass man sie leicht \u00fcbersehen kann, vor allem, wenn man Anf\u00e4nger ist. Ein winziger wei\u00dfer Punkt. Eine leicht eingerissene Flosse. Ein Fisch, [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":69217,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2824,1514],"tags":[3260,3262,3261,3259,3263],"class_list":["post-69242","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aquascaping-de","category-leitfaden-fur-einsteiger","tag-aquarium-pflege","tag-fisch-behandlung","tag-fisch-gesundheit","tag-fischkrankheiten","tag-haufige-probleme-im-aquarium"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>5 Krankheiten der Aquarienfische und ihre Behandlung - Bluviva%<\/title>\n<meta name=\"description\" content=\"Behandeln Sie wei\u00dfe Flecken, Flossenf\u00e4ule und mehr. Erfahren Sie, wie Sie eSHa EXIT und andere Behandlungen einsetzen k\u00f6nnen, um die 5 h\u00e4ufigsten Fischkrankheiten im Aquarium schnell zu heilen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bluviva.com\/de\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 Krankheiten der Aquarienfische und ihre Behandlung - Bluviva%\" \/>\n<meta property=\"og:description\" content=\"Behandeln Sie wei\u00dfe Flecken, Flossenf\u00e4ule und mehr. Erfahren Sie, wie Sie eSHa EXIT und andere Behandlungen einsetzen k\u00f6nnen, um die 5 h\u00e4ufigsten Fischkrankheiten im Aquarium schnell zu heilen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bluviva.com\/de\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\/\" \/>\n<meta property=\"og:site_name\" content=\"Bluviva\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61572180581409\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-13T17:54:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-21T20:33:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Blog-Thumbnail-Fish-Illness.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Lu\u00eds Cardoso\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lu\u00eds Cardoso\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bluviva.com\\\/de\\\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bluviva.com\\\/de\\\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\\\/\"},\"author\":{\"name\":\"Lu\u00eds Cardoso\",\"@id\":\"https:\\\/\\\/bluviva.com\\\/de\\\/#\\\/schema\\\/person\\\/51b96c936f5128b8e7618bb465ef0076\"},\"headline\":\"5 H\u00e4ufige Krankheiten bei Aquarienfischen (und wie man sie schnell und sicher behandelt)\",\"datePublished\":\"2026-02-13T17:54:24+00:00\",\"dateModified\":\"2026-04-21T20:33:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bluviva.com\\\/de\\\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\\\/\"},\"wordCount\":1631,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bluviva.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bluviva.com\\\/de\\\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bluviva.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Blog-Thumbnail-Fish-Illness.webp\",\"keywords\":[\"Aquarium Pflege\",\"Fisch Behandlung\",\"Fisch Gesundheit\",\"Fischkrankheiten\",\"H\u00e4ufige Probleme im Aquarium\"],\"articleSection\":[\"Aquascaping\",\"Leitfaden f\u00fcr Einsteiger\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bluviva.com\\\/de\\\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bluviva.com\\\/de\\\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\\\/\",\"url\":\"https:\\\/\\\/bluviva.com\\\/de\\\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\\\/\",\"name\":\"5 Krankheiten der Aquarienfische und ihre Behandlung - Bluviva%\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bluviva.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bluviva.com\\\/de\\\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bluviva.com\\\/de\\\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bluviva.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Blog-Thumbnail-Fish-Illness.webp\",\"datePublished\":\"2026-02-13T17:54:24+00:00\",\"dateModified\":\"2026-04-21T20:33:16+00:00\",\"description\":\"Behandeln Sie wei\u00dfe Flecken, Flossenf\u00e4ule und mehr. Erfahren Sie, wie Sie eSHa EXIT und andere Behandlungen einsetzen k\u00f6nnen, um die 5 h\u00e4ufigsten Fischkrankheiten im Aquarium schnell zu heilen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bluviva.com\\\/de\\\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bluviva.com\\\/de\\\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/bluviva.com\\\/de\\\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bluviva.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Blog-Thumbnail-Fish-Illness.webp\",\"contentUrl\":\"https:\\\/\\\/bluviva.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Blog-Thumbnail-Fish-Illness.webp\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bluviva.com\\\/de\\\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/bluviva.com\\\/de\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5 H\u00e4ufige Krankheiten bei Aquarienfischen (und wie man sie schnell und sicher behandelt)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bluviva.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/bluviva.com\\\/de\\\/\",\"name\":\"Bluviva\",\"description\":\"Online Aquarium Shop\",\"publisher\":{\"@id\":\"https:\\\/\\\/bluviva.com\\\/de\\\/#organization\"},\"alternateName\":\"Bluviva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bluviva.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bluviva.com\\\/de\\\/#organization\",\"name\":\"Bluviva\",\"url\":\"https:\\\/\\\/bluviva.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/bluviva.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bluviva.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/474620657_122101559012739352_4098091748390755316_n.webp\",\"contentUrl\":\"https:\\\/\\\/bluviva.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/474620657_122101559012739352_4098091748390755316_n.webp\",\"width\":200,\"height\":200,\"caption\":\"Bluviva\"},\"image\":{\"@id\":\"https:\\\/\\\/bluviva.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61572180581409\",\"https:\\\/\\\/www.youtube.com\\\/@Bluviva\",\"https:\\\/\\\/www.instagram.com\\\/bluvivaeu\\\/\",\"https:\\\/\\\/pinterest.com\\\/bluviva\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bluviva.com\\\/de\\\/#\\\/schema\\\/person\\\/51b96c936f5128b8e7618bb465ef0076\",\"name\":\"Lu\u00eds Cardoso\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8aabb486cf5b79411b73209fadee71f4c092d378c1a935140685bddeb49f1c00?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8aabb486cf5b79411b73209fadee71f4c092d378c1a935140685bddeb49f1c00?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8aabb486cf5b79411b73209fadee71f4c092d378c1a935140685bddeb49f1c00?s=96&d=mm&r=g\",\"caption\":\"Lu\u00eds Cardoso\"},\"url\":\"https:\\\/\\\/bluviva.com\\\/de\\\/author\\\/cardoso\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5 Krankheiten der Aquarienfische und ihre Behandlung - Bluviva%","description":"Behandeln Sie wei\u00dfe Flecken, Flossenf\u00e4ule und mehr. Erfahren Sie, wie Sie eSHa EXIT und andere Behandlungen einsetzen k\u00f6nnen, um die 5 h\u00e4ufigsten Fischkrankheiten im Aquarium schnell zu heilen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bluviva.com\/de\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\/","og_locale":"de_DE","og_type":"article","og_title":"5 Krankheiten der Aquarienfische und ihre Behandlung - Bluviva%","og_description":"Behandeln Sie wei\u00dfe Flecken, Flossenf\u00e4ule und mehr. Erfahren Sie, wie Sie eSHa EXIT und andere Behandlungen einsetzen k\u00f6nnen, um die 5 h\u00e4ufigsten Fischkrankheiten im Aquarium schnell zu heilen.","og_url":"https:\/\/bluviva.com\/de\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\/","og_site_name":"Bluviva","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61572180581409","article_published_time":"2026-02-13T17:54:24+00:00","article_modified_time":"2026-04-21T20:33:16+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Blog-Thumbnail-Fish-Illness.webp","type":"image\/png"}],"author":"Lu\u00eds Cardoso","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Lu\u00eds Cardoso","Gesch\u00e4tzte Lesezeit":"8 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bluviva.com\/de\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\/#article","isPartOf":{"@id":"https:\/\/bluviva.com\/de\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\/"},"author":{"name":"Lu\u00eds Cardoso","@id":"https:\/\/bluviva.com\/de\/#\/schema\/person\/51b96c936f5128b8e7618bb465ef0076"},"headline":"5 H\u00e4ufige Krankheiten bei Aquarienfischen (und wie man sie schnell und sicher behandelt)","datePublished":"2026-02-13T17:54:24+00:00","dateModified":"2026-04-21T20:33:16+00:00","mainEntityOfPage":{"@id":"https:\/\/bluviva.com\/de\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\/"},"wordCount":1631,"commentCount":0,"publisher":{"@id":"https:\/\/bluviva.com\/de\/#organization"},"image":{"@id":"https:\/\/bluviva.com\/de\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\/#primaryimage"},"thumbnailUrl":"https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Blog-Thumbnail-Fish-Illness.webp","keywords":["Aquarium Pflege","Fisch Behandlung","Fisch Gesundheit","Fischkrankheiten","H\u00e4ufige Probleme im Aquarium"],"articleSection":["Aquascaping","Leitfaden f\u00fcr Einsteiger"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bluviva.com\/de\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bluviva.com\/de\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\/","url":"https:\/\/bluviva.com\/de\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\/","name":"5 Krankheiten der Aquarienfische und ihre Behandlung - Bluviva%","isPartOf":{"@id":"https:\/\/bluviva.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bluviva.com\/de\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\/#primaryimage"},"image":{"@id":"https:\/\/bluviva.com\/de\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\/#primaryimage"},"thumbnailUrl":"https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Blog-Thumbnail-Fish-Illness.webp","datePublished":"2026-02-13T17:54:24+00:00","dateModified":"2026-04-21T20:33:16+00:00","description":"Behandeln Sie wei\u00dfe Flecken, Flossenf\u00e4ule und mehr. Erfahren Sie, wie Sie eSHa EXIT und andere Behandlungen einsetzen k\u00f6nnen, um die 5 h\u00e4ufigsten Fischkrankheiten im Aquarium schnell zu heilen.","breadcrumb":{"@id":"https:\/\/bluviva.com\/de\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bluviva.com\/de\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bluviva.com\/de\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\/#primaryimage","url":"https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Blog-Thumbnail-Fish-Illness.webp","contentUrl":"https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Blog-Thumbnail-Fish-Illness.webp","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/bluviva.com\/de\/5-haeufige-krankheiten-bei-aquarienfischen-und-wie-man-sie-schnell-und-sicher-behandelt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/bluviva.com\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"5 H\u00e4ufige Krankheiten bei Aquarienfischen (und wie man sie schnell und sicher behandelt)"}]},{"@type":"WebSite","@id":"https:\/\/bluviva.com\/de\/#website","url":"https:\/\/bluviva.com\/de\/","name":"Bluviva","description":"Online Aquarium Shop","publisher":{"@id":"https:\/\/bluviva.com\/de\/#organization"},"alternateName":"Bluviva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bluviva.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/bluviva.com\/de\/#organization","name":"Bluviva","url":"https:\/\/bluviva.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bluviva.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/bluviva.com\/wp-content\/uploads\/2025\/10\/474620657_122101559012739352_4098091748390755316_n.webp","contentUrl":"https:\/\/bluviva.com\/wp-content\/uploads\/2025\/10\/474620657_122101559012739352_4098091748390755316_n.webp","width":200,"height":200,"caption":"Bluviva"},"image":{"@id":"https:\/\/bluviva.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61572180581409","https:\/\/www.youtube.com\/@Bluviva","https:\/\/www.instagram.com\/bluvivaeu\/","https:\/\/pinterest.com\/bluviva\/"]},{"@type":"Person","@id":"https:\/\/bluviva.com\/de\/#\/schema\/person\/51b96c936f5128b8e7618bb465ef0076","name":"Lu\u00eds Cardoso","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/8aabb486cf5b79411b73209fadee71f4c092d378c1a935140685bddeb49f1c00?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8aabb486cf5b79411b73209fadee71f4c092d378c1a935140685bddeb49f1c00?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8aabb486cf5b79411b73209fadee71f4c092d378c1a935140685bddeb49f1c00?s=96&d=mm&r=g","caption":"Lu\u00eds Cardoso"},"url":"https:\/\/bluviva.com\/de\/author\/cardoso\/"}]}},"jetpack_featured_media_url":"https:\/\/bluviva.com\/wp-content\/uploads\/2026\/02\/Blog-Thumbnail-Fish-Illness.webp","_links":{"self":[{"href":"https:\/\/bluviva.com\/de\/wp-json\/wp\/v2\/posts\/69242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bluviva.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bluviva.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bluviva.com\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/bluviva.com\/de\/wp-json\/wp\/v2\/comments?post=69242"}],"version-history":[{"count":3,"href":"https:\/\/bluviva.com\/de\/wp-json\/wp\/v2\/posts\/69242\/revisions"}],"predecessor-version":[{"id":69281,"href":"https:\/\/bluviva.com\/de\/wp-json\/wp\/v2\/posts\/69242\/revisions\/69281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bluviva.com\/de\/wp-json\/wp\/v2\/media\/69217"}],"wp:attachment":[{"href":"https:\/\/bluviva.com\/de\/wp-json\/wp\/v2\/media?parent=69242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bluviva.com\/de\/wp-json\/wp\/v2\/categories?post=69242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bluviva.com\/de\/wp-json\/wp\/v2\/tags?post=69242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}